{"id":42,"count":6,"description":"lista delle magie castabili","link":"https:\/\/www.zhi.it\/portalnew\/category\/zhi-wiki\/pg\/spells\/","name":"Spells","slug":"spells","taxonomy":"category","parent":13,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spells Archivi - Zulu Hotel Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zhi.it\/portalnew\/category\/zhi-wiki\/pg\/spells\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spells Archivi - Zulu Hotel Italia\" \/>\n<meta property=\"og:description\" content=\"lista delle magie castabili\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zhi.it\/portalnew\/category\/zhi-wiki\/pg\/spells\/\" \/>\n<meta property=\"og:site_name\" content=\"Zulu Hotel Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/category\\\/zhi-wiki\\\/pg\\\/spells\\\/\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/category\\\/zhi-wiki\\\/pg\\\/spells\\\/\",\"name\":\"Spells Archivi - Zulu Hotel Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/category\\\/zhi-wiki\\\/pg\\\/spells\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/category\\\/zhi-wiki\\\/pg\\\/spells\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zhi-Wiki\",\"item\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/category\\\/zhi-wiki\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Personaggio\",\"item\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/category\\\/zhi-wiki\\\/pg\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Spells\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#website\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/\",\"name\":\"Zulu Hotel Italia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#organization\",\"name\":\"Zulu Hotel Italia\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-zhi-logo-colorato.png\",\"contentUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-zhi-logo-colorato.png\",\"width\":325,\"height\":325,\"caption\":\"Zulu Hotel Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spells Archivi - Zulu Hotel Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zhi.it\/portalnew\/category\/zhi-wiki\/pg\/spells\/","og_locale":"it_IT","og_type":"article","og_title":"Spells Archivi - Zulu Hotel Italia","og_description":"lista delle magie castabili","og_url":"https:\/\/www.zhi.it\/portalnew\/category\/zhi-wiki\/pg\/spells\/","og_site_name":"Zulu Hotel Italia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.zhi.it\/portalnew\/category\/zhi-wiki\/pg\/spells\/","url":"https:\/\/www.zhi.it\/portalnew\/category\/zhi-wiki\/pg\/spells\/","name":"Spells Archivi - Zulu Hotel Italia","isPartOf":{"@id":"https:\/\/www.zhi.it\/portalnew\/#website"},"breadcrumb":{"@id":"https:\/\/www.zhi.it\/portalnew\/category\/zhi-wiki\/pg\/spells\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zhi.it\/portalnew\/category\/zhi-wiki\/pg\/spells\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zhi.it\/portalnew\/"},{"@type":"ListItem","position":2,"name":"Zhi-Wiki","item":"https:\/\/www.zhi.it\/portalnew\/category\/zhi-wiki\/"},{"@type":"ListItem","position":3,"name":"Personaggio","item":"https:\/\/www.zhi.it\/portalnew\/category\/zhi-wiki\/pg\/"},{"@type":"ListItem","position":4,"name":"Spells"}]},{"@type":"WebSite","@id":"https:\/\/www.zhi.it\/portalnew\/#website","url":"https:\/\/www.zhi.it\/portalnew\/","name":"Zulu Hotel Italia","description":"","publisher":{"@id":"https:\/\/www.zhi.it\/portalnew\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zhi.it\/portalnew\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.zhi.it\/portalnew\/#organization","name":"Zulu Hotel Italia","url":"https:\/\/www.zhi.it\/portalnew\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/logo\/image\/","url":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/cropped-zhi-logo-colorato.png","contentUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/cropped-zhi-logo-colorato.png","width":325,"height":325,"caption":"Zulu Hotel Italia"},"image":{"@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/categories\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/categories\/13"}],"wp:post_type":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts?categories=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}