{"id":110,"date":"2015-10-09T13:57:43","date_gmt":"2015-10-09T13:57:43","guid":{"rendered":"http:\/\/www.linkwebsrl.it\/wordpress\/?p=110"},"modified":"2018-02-07T14:25:54","modified_gmt":"2018-02-07T14:25:54","slug":"bard","status":"publish","type":"post","link":"https:\/\/www.zhi.it\/portalnew\/bard\/","title":{"rendered":"Bard"},"content":{"rendered":"<p class=\"Stile18\">La loro musica pu\u00f2 essere un piacevole strumento di intrattenimento che un&#8217;arma micidiale nel combattimento. I bardi sono dotati di una grande intelligenza e sono capaci di decifrare delle mappe anche molto complicate.<\/p>\n<p class=\"Stile18\" style=\"text-align: center;\"><span class=\"inline inline-center\"><img loading=\"lazy\" decoding=\"async\" class=\"image image-_original\" title=\"\" src=\"https:\/\/www.zhi.it\/portalnew\/images\/bard.png\" alt=\"\" width=\"266\" height=\"329\" \/><\/span><\/p>\n<p class=\"Stile18\" style=\"text-align: center;\">Skill di Classe: Cartography, Enticement, Hiding, Musicianship, Peacemaking, Provocation<\/p>\n<p class=\"Stile18\">I bardi sono persone per lo pi\u00f9 miti e pacifiche. La gente li chiama \u201csuonatori\u201d, \u201cmusici\u201d, \u201ccantori\u201d. Li vedi nelle piazze delle citt\u00e0 a cantare gesta di eroi, leggende, divinit\u00e0,accompagnando la storia con una dolce melodia prodotta dai loro strumenti, arpe o liuti o tamburelli. Il bardo \u00e8 una\u00a0 figura molto ambivalente, pu\u00f2 essere un \u201caccattone\u201d che sfrutta la sua bella voce e la sua vena artistica per racimolare qualche soldo da tirare a campare oppure pu\u00f2 essere un suonatore nelle ville, palazzi,castelli di re,regine,lord o sindaci. La figura del bardo ha sempre portato gioia e allegria in chi lo vedeva,o piet\u00e0 per le misere condizioni di vita e comprensione per quella figura che da sempre ci allieta le giornate. Questa figura ora incute anche paura,timore se non altro. La riscoperta del Tomo delle antiche melodie,scritto da Morfeo,ha reso il bardo un&#8217;abile macchina da guerra.<br \/>\nOltre alle capacit\u00e0 proprie della sua musica,capace di perforare il cervello di chi l&#8217;ascolta, animale o persona o demone che sia, tanto da piegarla ai suoi voleri appacificandone gli intenti,oppure provocando in essa rabbia. Grazie alle melodie antiche di Morfeo il bardo sa potenziarsi,curarsi le ferite, rendere la sua carne dura come il metallo,sdoppiarsi per depistare il nemico o farlo cadere in trappola, disarcionare un inseguitore, bloccare gli arti di un avversario, persino resuscitare un amico caduto. In questa era \u00e8 ormai difficile trovare un bardo che si presti a fare il cantastorie, ma a noi malinconici piace ricordarli cosi.<\/p>\n<p class=\"Stile18\">Il bardo \u00e8 da sempre una figura\u00a0buona,ma dalla riesumazione del Tomo di Morfeo, il bardo \u00e8\u00a0diventato anche un valente condottiero di sventura.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><span class=\"Stile18\"><strong>Caratteristiche di classe:<\/strong><\/span><\/p>\n<ul>\n<li><span class=\"Stile18\">Pu\u00f2 indossare armature in materiale fino alla Chainmail eccezzion fatta per le Fruity.<\/span><\/li>\n<li><span class=\"Stile18\">Strumenti musicali (liuto, lira, sonagli, tamburo, arpa*) *quest&#8217;ultima arpa grande non permette di usare le skills ne il tomo delle antiche melodie. (si trovano nei negozi per i bardi o si craftano)<\/span><\/li>\n<li><span class=\"Stile18\">Tomo delle antiche melodie (acquistabile dallo spirito di Morfeo).<\/span><\/li>\n<li><span class=\"Stile18\">Pu\u00f2 utilizzare ogni tipo di arma (le skills di questa sono da considerarsi out class).<\/span><\/li>\n<li><span class=\"Stile18\">Non pu\u00f2 castare oltre il terzo circolo dello spellbook. <\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Per ulteriori informazioni consultate la sezione &gt;Music &amp; Bard System<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La loro musica pu\u00f2 essere un piacevole strumento di intrattenimento che un&#8217;arma micidiale nel combattimento. I bardi sono dotati di una grande intelligenza e sono capaci di decifrare delle mappe anche molto complicate. Skill di Classe: Cartography, Enticement, Hiding, Musicianship, Peacemaking, Provocation I bardi sono persone per lo pi\u00f9 miti e pacifiche. La gente li [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3026,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[21,22],"class_list":["post-110","post","type-post","status-publish","format-standard","has-post-thumbnail","category-uncategorized","tag-bard","tag-classi","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bard - Zulu Hotel Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zhi.it\/portalnew\/bard\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bard - Zulu Hotel Italia\" \/>\n<meta property=\"og:description\" content=\"La loro musica pu\u00f2 essere un piacevole strumento di intrattenimento che un&#8217;arma micidiale nel combattimento. I bardi sono dotati di una grande intelligenza e sono capaci di decifrare delle mappe anche molto complicate. Skill di Classe: Cartography, Enticement, Hiding, Musicianship, Peacemaking, Provocation I bardi sono persone per lo pi\u00f9 miti e pacifiche. La gente li [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zhi.it\/portalnew\/bard\/\" \/>\n<meta property=\"og:site_name\" content=\"Zulu Hotel Italia\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-09T13:57:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-07T14:25:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2017\/07\/bard.png\" \/>\n\t<meta property=\"og:image:width\" content=\"266\" \/>\n\t<meta property=\"og:image:height\" content=\"329\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ZHI Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZHI Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bard\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bard\\\/\"},\"author\":{\"name\":\"ZHI Staff\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/person\\\/3253a65b924bfa4cea859d5b8593a938\"},\"headline\":\"Bard\",\"datePublished\":\"2015-10-09T13:57:43+00:00\",\"dateModified\":\"2018-02-07T14:25:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bard\\\/\"},\"wordCount\":418,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/bard.png\",\"keywords\":[\"Bard\",\"Classi\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bard\\\/\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bard\\\/\",\"name\":\"Bard - Zulu Hotel Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bard\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/bard.png\",\"datePublished\":\"2015-10-09T13:57:43+00:00\",\"dateModified\":\"2018-02-07T14:25:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bard\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bard\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bard\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/bard.png\",\"contentUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/bard.png\",\"width\":266,\"height\":329},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bard\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#website\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/\",\"name\":\"Zulu Hotel Italia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#organization\",\"name\":\"Zulu Hotel Italia\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-zhi-logo-colorato.png\",\"contentUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-zhi-logo-colorato.png\",\"width\":325,\"height\":325,\"caption\":\"Zulu Hotel Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/person\\\/3253a65b924bfa4cea859d5b8593a938\",\"name\":\"ZHI Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g\",\"caption\":\"ZHI Staff\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bard - Zulu Hotel Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zhi.it\/portalnew\/bard\/","og_locale":"it_IT","og_type":"article","og_title":"Bard - Zulu Hotel Italia","og_description":"La loro musica pu\u00f2 essere un piacevole strumento di intrattenimento che un&#8217;arma micidiale nel combattimento. I bardi sono dotati di una grande intelligenza e sono capaci di decifrare delle mappe anche molto complicate. Skill di Classe: Cartography, Enticement, Hiding, Musicianship, Peacemaking, Provocation I bardi sono persone per lo pi\u00f9 miti e pacifiche. La gente li [&hellip;]","og_url":"https:\/\/www.zhi.it\/portalnew\/bard\/","og_site_name":"Zulu Hotel Italia","article_published_time":"2015-10-09T13:57:43+00:00","article_modified_time":"2018-02-07T14:25:54+00:00","og_image":[{"width":266,"height":329,"url":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2017\/07\/bard.png","type":"image\/png"}],"author":"ZHI Staff","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ZHI Staff","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zhi.it\/portalnew\/bard\/#article","isPartOf":{"@id":"https:\/\/www.zhi.it\/portalnew\/bard\/"},"author":{"name":"ZHI Staff","@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/person\/3253a65b924bfa4cea859d5b8593a938"},"headline":"Bard","datePublished":"2015-10-09T13:57:43+00:00","dateModified":"2018-02-07T14:25:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zhi.it\/portalnew\/bard\/"},"wordCount":418,"publisher":{"@id":"https:\/\/www.zhi.it\/portalnew\/#organization"},"image":{"@id":"https:\/\/www.zhi.it\/portalnew\/bard\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2017\/07\/bard.png","keywords":["Bard","Classi"],"articleSection":["Uncategorized"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.zhi.it\/portalnew\/bard\/","url":"https:\/\/www.zhi.it\/portalnew\/bard\/","name":"Bard - Zulu Hotel Italia","isPartOf":{"@id":"https:\/\/www.zhi.it\/portalnew\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zhi.it\/portalnew\/bard\/#primaryimage"},"image":{"@id":"https:\/\/www.zhi.it\/portalnew\/bard\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2017\/07\/bard.png","datePublished":"2015-10-09T13:57:43+00:00","dateModified":"2018-02-07T14:25:54+00:00","breadcrumb":{"@id":"https:\/\/www.zhi.it\/portalnew\/bard\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zhi.it\/portalnew\/bard\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.zhi.it\/portalnew\/bard\/#primaryimage","url":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2017\/07\/bard.png","contentUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2017\/07\/bard.png","width":266,"height":329},{"@type":"BreadcrumbList","@id":"https:\/\/www.zhi.it\/portalnew\/bard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zhi.it\/portalnew\/"},{"@type":"ListItem","position":2,"name":"Bard"}]},{"@type":"WebSite","@id":"https:\/\/www.zhi.it\/portalnew\/#website","url":"https:\/\/www.zhi.it\/portalnew\/","name":"Zulu Hotel Italia","description":"","publisher":{"@id":"https:\/\/www.zhi.it\/portalnew\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zhi.it\/portalnew\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.zhi.it\/portalnew\/#organization","name":"Zulu Hotel Italia","url":"https:\/\/www.zhi.it\/portalnew\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/logo\/image\/","url":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/cropped-zhi-logo-colorato.png","contentUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/cropped-zhi-logo-colorato.png","width":325,"height":325,"caption":"Zulu Hotel Italia"},"image":{"@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/person\/3253a65b924bfa4cea859d5b8593a938","name":"ZHI Staff","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g","caption":"ZHI Staff"}}]}},"_links":{"self":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":1,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts\/110\/revisions"}],"predecessor-version":[{"id":4626,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts\/110\/revisions\/4626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/media\/3026"}],"wp:attachment":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/media?parent=110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/categories?post=110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/tags?post=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}