{"id":5147,"date":"2018-09-28T09:54:11","date_gmt":"2018-09-28T09:54:11","guid":{"rendered":"https:\/\/www.zhi.it\/portalnew\/?p=5147"},"modified":"2024-09-09T23:31:16","modified_gmt":"2024-09-09T21:31:16","slug":"bomberman-arena","status":"publish","type":"post","link":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/","title":{"rendered":"Bomberman Arena"},"content":{"rendered":"<p>Ore 18.00 04\/10\/18<br \/>\nMini-Gioco<br \/>\nRegolamento:<br \/>\nNumero pg ammessi per gilda da minimo 1 (uno)<br \/>\nE\u2019 da considerarsi una gara singola. I PG dovranno presentarsi nudi, con back pack vuoto e appiedati. Verranno date in dotazione 50 pozze explosion a testa. Durante il gioco spawneranno delle robe di diverso colore nell&#8217;arena, ogni robe se indossata dar\u00e0 una particolarit\u00e0 e dei poteri, una volta usata questa si autodistrugger\u00e0. E\u2019 vietato l\u2019 utilizzo di qualsiasi skill, l\u2019 unica cosa concessa \u00e8 uccidere gli avversari con le pozze explosion. La trasgressione di una delle regole comporta l\u2019 ammonizione del pg, l\u2019 espulsione dalla gara e 5 punti di penalit\u00e0 alla gilda appartenente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ore 18.00 04\/10\/18 Mini-Gioco Regolamento: Numero pg ammessi per gilda da minimo 1 (uno) E\u2019 da considerarsi una gara singola. I PG dovranno presentarsi nudi, con back pack vuoto e appiedati. Verranno date in dotazione 50 pozze explosion a testa. Durante il gioco spawneranno delle robe di diverso colore nell&#8217;arena, ogni robe se indossata dar\u00e0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5133,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[302],"tags":[],"class_list":["post-5147","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arcnews","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bomberman Arena - Zulu Hotel Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bomberman Arena - Zulu Hotel Italia\" \/>\n<meta property=\"og:description\" content=\"Ore 18.00 04\/10\/18 Mini-Gioco Regolamento: Numero pg ammessi per gilda da minimo 1 (uno) E\u2019 da considerarsi una gara singola. I PG dovranno presentarsi nudi, con back pack vuoto e appiedati. Verranno date in dotazione 50 pozze explosion a testa. Durante il gioco spawneranno delle robe di diverso colore nell&#8217;arena, ogni robe se indossata dar\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/\" \/>\n<meta property=\"og:site_name\" content=\"Zulu Hotel Italia\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-28T09:54:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-09T21:31:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/1537189792.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1055\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ZHI Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZHI Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bomberman-arena\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bomberman-arena\\\/\"},\"author\":{\"name\":\"ZHI Staff\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/person\\\/3253a65b924bfa4cea859d5b8593a938\"},\"headline\":\"Bomberman Arena\",\"datePublished\":\"2018-09-28T09:54:11+00:00\",\"dateModified\":\"2024-09-09T21:31:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bomberman-arena\\\/\"},\"wordCount\":105,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bomberman-arena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/1537189792.png\",\"articleSection\":[\"Archivio News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bomberman-arena\\\/\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bomberman-arena\\\/\",\"name\":\"Bomberman Arena - Zulu Hotel Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bomberman-arena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bomberman-arena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/1537189792.png\",\"datePublished\":\"2018-09-28T09:54:11+00:00\",\"dateModified\":\"2024-09-09T21:31:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bomberman-arena\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bomberman-arena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bomberman-arena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/1537189792.png\",\"contentUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/1537189792.png\",\"width\":1600,\"height\":1055},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/bomberman-arena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bomberman Arena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#website\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/\",\"name\":\"Zulu Hotel Italia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#organization\",\"name\":\"Zulu Hotel Italia\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-zhi-logo-colorato.png\",\"contentUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-zhi-logo-colorato.png\",\"width\":325,\"height\":325,\"caption\":\"Zulu Hotel Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/person\\\/3253a65b924bfa4cea859d5b8593a938\",\"name\":\"ZHI Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g\",\"caption\":\"ZHI Staff\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bomberman Arena - Zulu Hotel Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/","og_locale":"it_IT","og_type":"article","og_title":"Bomberman Arena - Zulu Hotel Italia","og_description":"Ore 18.00 04\/10\/18 Mini-Gioco Regolamento: Numero pg ammessi per gilda da minimo 1 (uno) E\u2019 da considerarsi una gara singola. I PG dovranno presentarsi nudi, con back pack vuoto e appiedati. Verranno date in dotazione 50 pozze explosion a testa. Durante il gioco spawneranno delle robe di diverso colore nell&#8217;arena, ogni robe se indossata dar\u00e0 [&hellip;]","og_url":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/","og_site_name":"Zulu Hotel Italia","article_published_time":"2018-09-28T09:54:11+00:00","article_modified_time":"2024-09-09T21:31:16+00:00","og_image":[{"width":1600,"height":1055,"url":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/1537189792.png","type":"image\/png"}],"author":"ZHI Staff","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ZHI Staff","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/#article","isPartOf":{"@id":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/"},"author":{"name":"ZHI Staff","@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/person\/3253a65b924bfa4cea859d5b8593a938"},"headline":"Bomberman Arena","datePublished":"2018-09-28T09:54:11+00:00","dateModified":"2024-09-09T21:31:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/"},"wordCount":105,"commentCount":0,"publisher":{"@id":"https:\/\/www.zhi.it\/portalnew\/#organization"},"image":{"@id":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/1537189792.png","articleSection":["Archivio News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/","url":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/","name":"Bomberman Arena - Zulu Hotel Italia","isPartOf":{"@id":"https:\/\/www.zhi.it\/portalnew\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/#primaryimage"},"image":{"@id":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/1537189792.png","datePublished":"2018-09-28T09:54:11+00:00","dateModified":"2024-09-09T21:31:16+00:00","breadcrumb":{"@id":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/#primaryimage","url":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/1537189792.png","contentUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/1537189792.png","width":1600,"height":1055},{"@type":"BreadcrumbList","@id":"https:\/\/www.zhi.it\/portalnew\/bomberman-arena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zhi.it\/portalnew\/"},{"@type":"ListItem","position":2,"name":"Bomberman Arena"}]},{"@type":"WebSite","@id":"https:\/\/www.zhi.it\/portalnew\/#website","url":"https:\/\/www.zhi.it\/portalnew\/","name":"Zulu Hotel Italia","description":"","publisher":{"@id":"https:\/\/www.zhi.it\/portalnew\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zhi.it\/portalnew\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.zhi.it\/portalnew\/#organization","name":"Zulu Hotel Italia","url":"https:\/\/www.zhi.it\/portalnew\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/logo\/image\/","url":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/cropped-zhi-logo-colorato.png","contentUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/cropped-zhi-logo-colorato.png","width":325,"height":325,"caption":"Zulu Hotel Italia"},"image":{"@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/person\/3253a65b924bfa4cea859d5b8593a938","name":"ZHI Staff","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g","caption":"ZHI Staff"}}]}},"_links":{"self":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts\/5147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/comments?post=5147"}],"version-history":[{"count":1,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts\/5147\/revisions"}],"predecessor-version":[{"id":5149,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts\/5147\/revisions\/5149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/media\/5133"}],"wp:attachment":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/media?parent=5147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/categories?post=5147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/tags?post=5147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}