{"id":5491,"date":"2018-10-27T08:55:34","date_gmt":"2018-10-27T08:55:34","guid":{"rendered":"https:\/\/www.zhi.it\/portalnew\/?p=5491"},"modified":"2024-09-09T23:40:51","modified_gmt":"2024-09-09T21:40:51","slug":"zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni","status":"publish","type":"post","link":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/","title":{"rendered":"ZHI Setup: guida alla soluzione dei problemi pi\u00f9 comuni"},"content":{"rendered":"<div style=\"text-align: justify !important;\">\n<h3>Guida alle problematiche pi\u00f9 frequenti durante l\u2019installazione e utilizzo di ZHI.<\/h3>\n<p><strong>Tipologia di problema: creo delle macro in game ma quando esco e rientro dal gioco queste non si salvano, oppure provo ad avviare le utility (UOLOOP, AUTOPILOT, UOSU..) queste non funzionano.<\/strong><\/p>\n<p>Quando viene avviata l\u2019installazione di ZHI su windows attraverso l\u2019apposito installer possono riscontrarsi vari problemi. <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5495 alignright\" src=\"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/10\/proprieta_win_ultimadir.png\" alt=\"\" width=\"363\" height=\"499\" srcset=\"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/10\/proprieta_win_ultimadir.png 363w, https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/10\/proprieta_win_ultimadir-218x300.png 218w\" sizes=\"auto, (max-width: 363px) 100vw, 363px\" \/><br \/>\nUna di questi riguarda i permessi della cartella Ultima Online 2D dove risiedono i files di gioco.<br \/>\nPer poter funzionare correttamente la cartella di ZHI deve avere i permessi di lettura\\scrittura. Solitamente il gioco viene installato in C:\\Program Files\\Ultima Online 2D ). Guardando le propriet\u00e0 di questa cartella (visibile facendo tasto \u201cdestro -&gt; propriet\u00e0\u201d su questa cartella) e <strong>posizionandosi sul proprio utente (quello con cui siete entrati sul pc), sar\u00e0 possibile vedere le operazioni che sono consentite. E\u2019 sufficiente che il vostro utente abbia le \u201cspunte\u201d su LETTURA, SCRITTURA, MODIFICA<\/strong> Qualora non siano presente queste spunte \u00e8 necessario aggiungerle facendo \u201cModifica\u201d. Ovviamente, qualora non siate \u201cAdministrator\u201d o \u201cSuperuser\u201d della macchina probabilmente questa operazione non sar\u00e0 possibile.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Per verificare se il proprio utente \u00e8 amministratore della macchina \u00e8 necessario cliccare su tasto START e digitate GESTISCI.<br \/>\nCliccare quindi su GESTISCI IL TUO ACCOUNT.<br \/>\nSi aprir\u00e0 una maschera con il proprio utente<\/p>\n<p>Cliccare poi su GESTISCI ACCOUNT UTENTE. Appena sotto il vostro nome, qualora siate amministratori, verr\u00e0 visualizzata la voce \u201cAmministratore\u201d (anche \u201csuperuser\u201d pu\u00f2 andare bene)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5496 aligncenter\" src=\"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/10\/impostazioni_utente_win10.png\" alt=\"\" width=\"638\" height=\"516\" srcset=\"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/10\/impostazioni_utente_win10.png 638w, https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/10\/impostazioni_utente_win10-300x243.png 300w\" sizes=\"auto, (max-width: 638px) 100vw, 638px\" \/><\/p>\n<p>Qualora ci sia invece scritto \u201cUtente\u201d , potreste non avere i diritti di modificare i permessi della cartella di ULTIMA ONLINE 2D.<br \/>\nPossiamo quindi agire in due modi:<\/p>\n<p>1) Entrare con un\u2019utenza amministrativa sul pc<br \/>\n2) Lanciare il file ZHIAutomaticFix.bat presente nella cartella \u201cXpasd\u201d all\u2019interno dell\u2019installazione di \u201cUltima Online 2D\u201d<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5497 aligncenter\" src=\"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/10\/zhi_automatic_fix.png\" alt=\"\" width=\"599\" height=\"196\" srcset=\"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/10\/zhi_automatic_fix.png 599w, https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/10\/zhi_automatic_fix-300x98.png 300w, https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/10\/zhi_automatic_fix-1230x400.png 1230w\" sizes=\"auto, (max-width: 599px) 100vw, 599px\" \/><\/p>\n<p>Questa operazione permette di sistemare tutti i permessi della cartella ULTIMA ONLINE 2D. Sui pc con windows 10 \u00e8 necessario eseguire questo file come amministratore (tasto destro sul ZHIAutomaticFix.bat -&gt; esegui come amministratore)<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Guida alle problematiche pi\u00f9 frequenti durante l\u2019installazione e utilizzo di ZHI. Tipologia di problema: creo delle macro in game ma quando esco e rientro dal gioco queste non si salvano, oppure provo ad avviare le utility (UOLOOP, AUTOPILOT, UOSU..) queste non funzionano. Quando viene avviata l\u2019installazione di ZHI su windows attraverso l\u2019apposito installer possono riscontrarsi [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4766,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[302],"tags":[],"class_list":["post-5491","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arcnews","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ZHI Setup: guida alla soluzione dei problemi pi\u00f9 comuni - Zulu Hotel Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZHI Setup: guida alla soluzione dei problemi pi\u00f9 comuni - Zulu Hotel Italia\" \/>\n<meta property=\"og:description\" content=\"Guida alle problematiche pi\u00f9 frequenti durante l\u2019installazione e utilizzo di ZHI. Tipologia di problema: creo delle macro in game ma quando esco e rientro dal gioco queste non si salvano, oppure provo ad avviare le utility (UOLOOP, AUTOPILOT, UOSU..) queste non funzionano. Quando viene avviata l\u2019installazione di ZHI su windows attraverso l\u2019apposito installer possono riscontrarsi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/\" \/>\n<meta property=\"og:site_name\" content=\"Zulu Hotel Italia\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-27T08:55:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-09T21:40:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2011\/02\/ultima-online-splash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZHI Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZHI Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\\\/\"},\"author\":{\"name\":\"ZHI Staff\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/person\\\/3253a65b924bfa4cea859d5b8593a938\"},\"headline\":\"ZHI Setup: guida alla soluzione dei problemi pi\u00f9 comuni\",\"datePublished\":\"2018-10-27T08:55:34+00:00\",\"dateModified\":\"2024-09-09T21:40:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\\\/\"},\"wordCount\":330,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/ultima-online-splash.jpg\",\"articleSection\":[\"Archivio News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\\\/\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\\\/\",\"name\":\"ZHI Setup: guida alla soluzione dei problemi pi\u00f9 comuni - Zulu Hotel Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/ultima-online-splash.jpg\",\"datePublished\":\"2018-10-27T08:55:34+00:00\",\"dateModified\":\"2024-09-09T21:40:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/ultima-online-splash.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/ultima-online-splash.jpg\",\"width\":1024,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ZHI Setup: guida alla soluzione dei problemi pi\u00f9 comuni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#website\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/\",\"name\":\"Zulu Hotel Italia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#organization\",\"name\":\"Zulu Hotel Italia\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-zhi-logo-colorato.png\",\"contentUrl\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-zhi-logo-colorato.png\",\"width\":325,\"height\":325,\"caption\":\"Zulu Hotel Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zhi.it\\\/portalnew\\\/#\\\/schema\\\/person\\\/3253a65b924bfa4cea859d5b8593a938\",\"name\":\"ZHI Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g\",\"caption\":\"ZHI Staff\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZHI Setup: guida alla soluzione dei problemi pi\u00f9 comuni - Zulu Hotel Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/","og_locale":"it_IT","og_type":"article","og_title":"ZHI Setup: guida alla soluzione dei problemi pi\u00f9 comuni - Zulu Hotel Italia","og_description":"Guida alle problematiche pi\u00f9 frequenti durante l\u2019installazione e utilizzo di ZHI. Tipologia di problema: creo delle macro in game ma quando esco e rientro dal gioco queste non si salvano, oppure provo ad avviare le utility (UOLOOP, AUTOPILOT, UOSU..) queste non funzionano. Quando viene avviata l\u2019installazione di ZHI su windows attraverso l\u2019apposito installer possono riscontrarsi [&hellip;]","og_url":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/","og_site_name":"Zulu Hotel Italia","article_published_time":"2018-10-27T08:55:34+00:00","article_modified_time":"2024-09-09T21:40:51+00:00","og_image":[{"width":1024,"height":650,"url":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2011\/02\/ultima-online-splash.jpg","type":"image\/jpeg"}],"author":"ZHI Staff","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ZHI Staff","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/#article","isPartOf":{"@id":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/"},"author":{"name":"ZHI Staff","@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/person\/3253a65b924bfa4cea859d5b8593a938"},"headline":"ZHI Setup: guida alla soluzione dei problemi pi\u00f9 comuni","datePublished":"2018-10-27T08:55:34+00:00","dateModified":"2024-09-09T21:40:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/"},"wordCount":330,"publisher":{"@id":"https:\/\/www.zhi.it\/portalnew\/#organization"},"image":{"@id":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2011\/02\/ultima-online-splash.jpg","articleSection":["Archivio News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/","url":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/","name":"ZHI Setup: guida alla soluzione dei problemi pi\u00f9 comuni - Zulu Hotel Italia","isPartOf":{"@id":"https:\/\/www.zhi.it\/portalnew\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/#primaryimage"},"image":{"@id":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2011\/02\/ultima-online-splash.jpg","datePublished":"2018-10-27T08:55:34+00:00","dateModified":"2024-09-09T21:40:51+00:00","breadcrumb":{"@id":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/#primaryimage","url":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2011\/02\/ultima-online-splash.jpg","contentUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2011\/02\/ultima-online-splash.jpg","width":1024,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/www.zhi.it\/portalnew\/zhi-setup-guida-alla-soluzione-dei-problemi-piu-comuni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zhi.it\/portalnew\/"},{"@type":"ListItem","position":2,"name":"ZHI Setup: guida alla soluzione dei problemi pi\u00f9 comuni"}]},{"@type":"WebSite","@id":"https:\/\/www.zhi.it\/portalnew\/#website","url":"https:\/\/www.zhi.it\/portalnew\/","name":"Zulu Hotel Italia","description":"","publisher":{"@id":"https:\/\/www.zhi.it\/portalnew\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zhi.it\/portalnew\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.zhi.it\/portalnew\/#organization","name":"Zulu Hotel Italia","url":"https:\/\/www.zhi.it\/portalnew\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/logo\/image\/","url":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/cropped-zhi-logo-colorato.png","contentUrl":"https:\/\/www.zhi.it\/portalnew\/wp-content\/uploads\/2018\/09\/cropped-zhi-logo-colorato.png","width":325,"height":325,"caption":"Zulu Hotel Italia"},"image":{"@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.zhi.it\/portalnew\/#\/schema\/person\/3253a65b924bfa4cea859d5b8593a938","name":"ZHI Staff","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d984da0771c87eed06de272bebc972e741e1f569ecc3e0fb66e3b7cb5670dbc5?s=96&d=mm&r=g","caption":"ZHI Staff"}}]}},"_links":{"self":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts\/5491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/comments?post=5491"}],"version-history":[{"count":2,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts\/5491\/revisions"}],"predecessor-version":[{"id":5499,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/posts\/5491\/revisions\/5499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/media\/4766"}],"wp:attachment":[{"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/media?parent=5491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/categories?post=5491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zhi.it\/portalnew\/wp-json\/wp\/v2\/tags?post=5491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}